{"id":238632,"date":"2022-09-30T15:39:49","date_gmt":"2022-09-30T13:39:49","guid":{"rendered":"https:\/\/rtrsports.com\/the-calendar-motogp-2023-new-race-and-sprint-race\/"},"modified":"2025-07-01T15:30:34","modified_gmt":"2025-07-01T13:30:34","slug":"the-calendar-motogp-2023-new-race-and-sprint-race","status":"publish","type":"post","link":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/","title":{"rendered":"The 2023 MotoGP Calendar. With new competitions and downloadable PDF."},"content":{"rendered":"<p class=\"ai-optimize-6 ai-optimize-introduction\">Mancano poche gare alla fine del <a href=\"https:\/\/rtrsports.com\/en\/sponsorships-motogp\/\"><strong>Campionato MotoGP<\/strong><\/a> 2022 e c\u2019\u00e8 gi\u00e0 molta curiosit\u00e0 e attesa per il calendario 2023. Dopo l\u2019uscita del <strong><a href=\"https:\/\/rtrsports.com\/en\/?p=238613\">calendario 2023 della Formula 1<\/a><\/strong>, sono sorte infatti molte domande e dubbi su quello che sar\u00e0 il tour delle due ruote. I due campionati, infatti, a volte corrono negli stessi circuiti e si devono quindi interfacciare e coordinare in modo da non coprire gli stessi territori nello stesso periodo.<\/p>\n<p class=\"ai-optimize-7\">La cosa che ha certamente destato grande attenzione quando \u00e8 uscito il calendario della <a href=\"https:\/\/rtrsports.com\/sponsorizzazioni-formula-1\/\"><strong>Formula 1<\/strong><\/a>, \u00e8 il numero di gare che la stagione 2023 si propone di coprire; un vero tour de force, il calendario pi\u00f9 lungo di sempre. 24 gare in nove mesi, da marzo a fine novembre, passando da un continente all\u2019altro con una sola lunga pausa in Agosto.<\/p>\n<p class=\"ai-optimize-8\">E la <strong>MotoGP?<\/strong> Quante gare ci sono e cosa cambia rispetto al calendario precedente?<\/p>\n<p class=\"ai-optimize-9\">Il calendario della MotoGP 2023 propone 21 gare, a partire dal Portogallo in marzo fino ad arrivare a Valencia verso la fine di novembre. E da qui capiamo subito quelle che sono le prime novit\u00e0 rispetto agli anni precedenti.<\/p>\n<h2 class=\"ai-optimize-10\">Calendario MotoGP 2023: niente Aragon e partenza dal Portogallo<\/h2>\n<p class=\"ai-optimize-11\">26 marzo: Portimao \/ <strong>Portogallo<\/strong><br \/>\n2 aprile: Termas de Rio Hondo \/ <strong>Argentina<\/strong><br \/>\n16 aprile: Austin\/ <strong>Stati Uniti<\/strong><br \/>\n30 aprile: Jerez \/ <strong>Spagna<\/strong><br \/>\n14 maggio: Le Mans \/ <strong>Francia<\/strong><br \/>\n11 giugno: Mugello \/ <strong>Italia<\/strong><br \/>\n18 giugno: Sachsenring \/ <strong>Germania<\/strong><br \/>\n25 giugno: Assen \/ <strong>Olanda<\/strong><br \/>\n9 luglio: Sokol \/ <strong>Kazakistan<\/strong><br \/>\n6 agosto: Silverstone \/ <strong>Gran Bretagna<\/strong><br \/>\n20 agosto: Spielberg \/ <strong>Austria<\/strong><br \/>\n3 settembre: Barcellona \/ <strong>Catalogna<\/strong><br \/>\n10 settembre: Misano \/ <strong>San Marino<\/strong><br \/>\n24 settembre: Buddh \/ <strong>India<\/strong><br \/>\n1 ottobre: Motegi \/ <strong>Giappone<\/strong><br \/>\n15 ottobre: Mandalika \/ <strong>Indonesia<\/strong><br \/>\n22 ottobre: Phillip Island \/ <strong>Australia<\/strong><br \/>\n29 ottobre: Buriram \/ <strong>Thailandia<\/strong><br \/>\n12 novembre: Sepang \/ <strong>Malesia<\/strong><br \/>\n19 novembre: Losail \/ <strong>Qatar<\/strong><br \/>\n26 novembre: Valencia \/ <strong>Valencia<\/strong><\/p>\n<h2 class=\"ai-optimize-12\">Il Calendario MotoGP 2023<\/h2>\n<p class=\"ai-optimize-13\">Il primo grande cambiamento inizia con la partenza del campionato stesso, con la prima gara della stagione. Il campionato della MotoGP da oltre dieci anni, con precisione dal 2007, ha sempre inaugurato la stagione con la gara in notturna in <strong>Qatar,<\/strong> dal circuito di Losail a Doha. Nel 2023 si parte invece dall\u2019Europa, e precisamente dal circuito di Portimao in Portogallo il 24 marzo, per poi volare subito dall\u2019altra parte del mondo, in Argentina e in America e rientrare in Europa con la classica gara spagnola a Jerez De la Frontera da sempre primo appuntamento europeo delle massimo campionato delle due ruote.<\/p>\n<p class=\"ai-optimize-14\">Seconda grande novit\u00e0 dell\u2019anno \u00a0riguarda una new entry: il 7 luglio si correr\u00e0 il <strong>Grand Prix del Kazakhstan<\/strong>, presso il nuovo circuito di Sokol ad Almaty, la citt\u00e0 pi\u00f9 grande del paese. In Kazakhstan si correr\u00e0 per i prossimi 5 anni, questa infatti \u00e8 la durata dell\u2019accordo siglato tra il circuito e <strong>Dorna.<\/strong> Il Kazakhstan diventa cos\u00ec il trentesimo paese ad ospitare una gara di MotoGP dal 1949, un traguardo veramente importante per il campionato di motorsport pi\u00f9 antico del mondo. E i record non finiscono qui; il bellissimo circuito di Sokol \u00e8 il 74esimo ad ospitare una gara di MotoGP.<\/p>\n<p class=\"ai-optimize-15\">Dopo questo nuovo Gp ci sar\u00e0 la classica pausa estiva di tre settimane per poi riprendere con altre 4 gare europee, <strong>Silverstone, Austria, Barcellona<\/strong> e <strong>San Marino<\/strong>.<\/p>\n<p class=\"ai-optimize-16\">La seconda grande novit\u00e0 in calendario \u00e8 <strong>l\u2019India.<\/strong> Dopo le quattro gare europee ci si trasferisce in India dove si \u00a0correr\u00e0 la quattordicesima gara del Motomondiale 2023, precisamente al Buddh International Circuit, situato nell&#8217;Uttar Pradesh a sud di <strong>Nuova Delhi.<\/strong><\/p>\n<p class=\"ai-optimize-17\">Introdurre una gara in India \u00e8 certamente un\u2019ottima scelta strategica; con una popolazione di oltre 1,4 miliardi di persone e pi\u00f9 di 200 milioni di motociclette sulle sue strade, l\u2019India rappresenta un mercato enorme sia in termini di audience per il campionato che in termini di visibilit\u00e0 per le aziende produttrici di moto che possono utilizzare la MotoGP come perfetto strumento di comunicazione sul territorio.<\/p>\n<p class=\"ai-optimize-18\">Come dice infatti il comunicato di <strong>MotoGP<\/strong> \u201cL&#8217;India \u00e8 una vera e propria potenza economica e culturale, Il trasporto su due ruote rappresenta quasi il 75% del numero totale di veicoli utilizzati quotidianamente, rendendo l&#8217;India uno dei pi\u00f9 grandi mercati motociclistici del mondo e un punto di riferimento fondamentale per i produttori del paddock della MotoGP\u2122.\u00a0 Correre al Buddh International Circuit, situato nell&#8217;Uttar Pradesh a sud di Nuova Delhi, porter\u00e0 lo sport nel cuore di questo mercato chiave e lo render\u00e0 pi\u00f9 accessibile che mai ai nostri fan in tutta la regione. Mentre la MotoGP\u2122 continua ad espandersi, il Gran Premio dell&#8217;India segna un&#8217;importante pietra miliare nella missione di questo sport di aprire le porte del motociclismo a tutti, scrivendo un nuovo capitolo nella storia del primo campionato automobilistico al mondo e accogliendo nuovi spettatori e fan da ogni angolo del mondo.\u201d<\/p>\n<p class=\"ai-optimize-19\">La gara indiana sar\u00e0 la prima di sette gare in Asia e Oceania (Giappone, Indonesia, Australia, Tailandia, Malesia e Qatar) la stagione poi terminer\u00e0 come sempre in Europa, a Valencia il 24 di novembre.<\/p>\n<p class=\"ai-optimize-20\">Altra novit\u00e0 per ci\u00f2 che riguarda i nuovi arrivi, \u00e8 l\u2019assenza della gara in <strong>Finlandia,<\/strong> inserita gi\u00e0 nel calendario del 2022 ma poi non disputata perch\u00e9 apparentemente il circuito non era ancora pronto. Si pensava che lo sarebbe stato nel giro di un anno ed invece si sono aggiunti altri problemi e quindi niente da fare, la Finlandia salta anche nel 2023.<\/p>\n<p class=\"ai-optimize-21\">Un calendario di 21 gare, molto intenso, con nuovi arrivi e tante conferme dal punto di vista dei circuiti.<\/p>\n<p class=\"ai-optimize-22\">C\u2019\u00e8 poi un aspetto importante da sottolineare per ci\u00f2 che riguarda il format di gara, soprattutto quello del sabato. Il vero elemento che cambia in modo impattante il format del campionato e quindi l\u2019intero weekend di prove e di gara, \u00e8 l\u2019introduzione della Sprint Race. Se ne \u00e8 parlato molto in queste settimane, spesso con poca chiarezza e con tanti dubbi. Vediamo quindi nel dettaglio di cosa si tratta e come funzioner\u00e0 questa nuova gara breve del Sabato.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large\" src=\"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-sponsor-2.jpg\" alt=\"motogp calendar 2023\" width=\"100%\" \/><\/p>\n<h2 class=\"ai-optimize-23\">La sprint race: perch\u00e9 \u00e8 stata inserita nel calendario MotoGP 2023 e ci sar\u00e0 in tutte le gare del calendario?<\/h2>\n<p class=\"ai-optimize-24\">La <strong>sprint race<\/strong> \u00e8 la grande novit\u00e0 del campionato MotoGP 2023, una vera e propria aggiunta al format a cui gli spettatori sono abituati praticamente da sempre. Una delle domande pi\u00f9 frequenti che riceviamo negli ultimi tempi quando parliamo di opportunit\u00e0 di sponsorizzazione sportiva nella MotoGP, \u00e8 proprio il perch\u00e9 dell\u2019introduzione di questa gara.<\/p>\n<p class=\"ai-optimize-25\">Dorna, l\u2019organizzatore del Campionato, ha sicuramente preso spunto dalla sorella a 4 ruote, la Formula 1, se non tanto per il format, per lo meno per l\u2019idea di introdurre qualcosa che aumentasse lo spettacolo e il programma del sabato. Soprattutto per chi partecipa di persona, come pubblico in tribuna, alle prove del sabato, e si lamenta della mancanza di uno spettacolo pi\u00f9 completo, come quello della domenica, e che trova quindi il programma del sabato meno entusiasmante e troppo breve.<\/p>\n<p class=\"ai-optimize-26\">E per eliminare questo punto debole che si \u00e8 pensato di replicare la sprint race anche nelle due ruote, ma di aggiungerla per\u00f2 a tutte le gare, non solo ad alcune come avviene in Formula 1.<\/p>\n<p class=\"ai-optimize-27\">Carlos Ezpeleta, Chief sporting Officer, ha infatti spiegato in una recente conferenza stampa in cui racconta i dettagli della sprint race, che la decisione di avere questa gara veloce in tutti le gare in calendario da l\u2019opportunit\u00e0 ai fan di familiarizzare meglio con il nuovo format e con gli orari, non fa differenze tra i GP, che per Dorna sono tutti importanti, e rendere tutto uniforme senza creare confusione.<\/p>\n<h3 class=\"ai-optimize-28\">Ma come funziona la spint race?<\/h3>\n<p class=\"ai-optimize-29\">Vediamolo nello specifico. Innanzitutto, diciamo subito che la sprint race si correr\u00e0 in tutte le gare, il <strong>sabato,<\/strong> dopo le qualifiche ufficiali che determinano la griglia di partenza della domenica; quindi, alle 15 di ogni sabato di gara.\u00a0 Questo \u00e8 un primo punto fondamentale da specificare: la sprint race non andr\u00e0 a influire e quindi a modificare la griglia di partenza della gara della domenica, che si determina come sempre il sabato con le qualifiche ufficiali.<\/p>\n<p class=\"ai-optimize-30\">Quindi Q1 e Q2 determinano infatti sia la griglia di partenza della gara della domenica, sia la <strong>griglia di partenza<\/strong> della Sprint Race del sabato pomeriggio.<\/p>\n<p><img decoding=\"async\" class=\"size-large aligncenter\" src=\"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/08\/-7Q-7\" width=\"100%\" \/><\/p>\n<h3 class=\"ai-optimize-31\">La sprint race \u00e8 una gara vera e propria?<\/h3>\n<p class=\"ai-optimize-32\">La <strong>sprint race<\/strong> \u00e8 una gara a tutti gli effetti, con una griglia di partenza e un podio che garantir\u00e0 di segnare dei punti validi per il campionato. La sprint race durer\u00e0 la met\u00e0 dei giri della gara della domenica, quindi circa 20 minuti rispetto ai 40 della gara completa. Ecco il sistema con cui saranno assegnati i punti: 12 per il vincitore, 9 per il secondo posto, 7 per il terzo. E a scalare fino ad arrivare al nono piazzamento.<\/p>\n<p class=\"ai-optimize-33\">Altre novit\u00e0, sia per i team che per i piloti, che per il pubblico in pista e davanti allo schermo, sono gli orari e il programma generale del sabato. Vediamo come sar\u00e0 articolato il weekend a partire dal venerd\u00ec.<\/p>\n<h2 class=\"ai-optimize-34\">Il nuovo format della MotoGP dal 2023:<\/h2>\n<p class=\"ai-optimize-35\">Con il Calendario MotoGP 2023 cambia radicalmente anche la composizione del weekend di gara, che vede nella giornata di sabato i maggiori cambiamenti.<\/p>\n<h3 class=\"ai-optimize-36\"><strong>VENERDI&#8217;<\/strong><\/h3>\n<ul>\n<li class=\"ai-optimize-37\">9.00 35 minuti Moto3 Practice 1 (questa sessione sar\u00e0 pi\u00f9 breve di 5 minuti rispetto a quella degli anni precedenti)<\/li>\n<li class=\"ai-optimize-38\">9.50 40 minuti Moto2 Practice 1<\/li>\n<li class=\"ai-optimize-39\">10.45 45 minuti MotoGP Practice 1<\/li>\n<li class=\"ai-optimize-40\">13.15 35 minuti Moto3 Practice 2<\/li>\n<li class=\"ai-optimize-41\">14.05 40 minuti Moto2 Practice 2<\/li>\n<li class=\"ai-optimize-42\">15.00 60 minuti MotoGP Practice 2 (un\u2019ora intera, quindi pi\u00f9 tempo rispetto al programma degli anni precedenti)<\/li>\n<\/ul>\n<h3 class=\"ai-optimize-43\"><strong>SABATO<\/strong><\/h3>\n<p class=\"ai-optimize-44\">\u00c8 qui che si vedono i cambiamenti maggiori. La giornata inizia prima, alle 8.40<\/p>\n<ul>\n<li class=\"ai-optimize-45\">8.40 30 minuti Moto3 Free Practice<\/li>\n<li class=\"ai-optimize-46\">9.25 30 minuti Moto2 Free Practice<\/li>\n<li class=\"ai-optimize-47\">10.10 30 minuti MotoGP Free practice<\/li>\n<li class=\"ai-optimize-48\">10.50 15 minuti MotoGP Qualifying 1<\/li>\n<li class=\"ai-optimize-49\">11.15 15 minuti MotoGP Qualifying 2<\/li>\n<li class=\"ai-optimize-50\">12.55 15 minuti Moto3 Qualifying 1<\/li>\n<li class=\"ai-optimize-51\">13.20 15 minuti Moto3 Qualifying 2<\/li>\n<li class=\"ai-optimize-52\">13.50 15 minuti Moto2 Qualifying 1<\/li>\n<li class=\"ai-optimize-53\">14.15 15 minuti Moto2 Qualifying 2<\/li>\n<li class=\"ai-optimize-54\">15.00 20 minuti Sprint Race con un suo podio indipendente dalla gara del giorno dopo, in una posizione diversa rispetto a quello attuale. Questi aspetti sono ancora in via di definizione.<\/li>\n<\/ul>\n<h3 class=\"ai-optimize-55\"><strong>DOMENICA<\/strong><\/h3>\n<ul>\n<li class=\"ai-optimize-56\">9.40 10 minuti MotoGP Warm Up quindi pi\u00f9 breve al solito<\/li>\n<li class=\"ai-optimize-57\">10.00 30 minuti <strong>MotoGP rider fan zone<\/strong>: altra grande novit\u00e0 che prende il via con il Calendario MotoGP 2023 per creare un po&#8217; di interazione con i fans \u00e8 quella della <a href=\"https:\/\/www.misanocircuit.com\/motogpfanzone\/\">MotoGP rider fan zone<\/a>. Questo \u00e8 certamente un aspetto che manca attualmente in MotoGP e che \u00e8 da migliorare, a grande richiesta da parte del pubblico. L\u2019 engagement con il pubblico \u00e8 fondamentale, basta guardare per esempio quello che cerca di fare la Formula 1 che ha il giro del circuito dei piloti che salutano gli spettatori sugli spalti; anche se sono lontani \u00e8 un modo per avvicinare tutti i fans che accorrono in pista anche per poter vedere i piloti, non solo le auto che sfrecciano. In generale, i piloti della Formula 1 sono certamente pi\u00f9 impegnati e attivi a livello di engagement con il pubblico.<\/li>\n<li class=\"ai-optimize-58\">11.00 Moto3 GP Race<\/li>\n<li class=\"ai-optimize-59\">12.15 Moto2 GP Race<\/li>\n<li class=\"ai-optimize-60\">14.00 Race<\/li>\n<\/ul>\n<p class=\"ai-optimize-61\">La sprint race sar\u00e0 ristretta a 12 piloti e avr\u00e0 le stesse identiche regole della gara normale. Come si vede, il programma del sabato \u00e8 nettamente aumentato e la giornata \u00e8 veramente molto piena. Il pubblico avr\u00e0 uno spettacolo in pista costane dalle 8.40 fino almeno alle 15.45.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/marc-marquez-2.jpg\" alt=\"MotoGP calendar 2023\" width=\"100%\" \/><\/p>\n<h3 class=\"ai-optimize-62\">Perch\u00e9 l\u2019introduzione della Sprint Race in MotoGP sta creando tante polemiche soprattutto trai team e i piloti?<\/h3>\n<p class=\"ai-optimize-63\">Uno dei primi aspetti su cui chi lavora in <a href=\"https:\/\/motogp.com\/\"><strong>MotoGP<\/strong><\/a>, team e piloti nello specifico, ha dei forti dubbi, \u00e8 lo stress a cui saranno sottoposti i piloti dovendo correre una gara in pi\u00f9, anche se pi\u00f9 corta. Non si tratta infatti di considerare \u201csolo\u201d i 20 minuti di gara effettiva, ma tutto quello che avviene prima e la stanchezza e lo stress che il pilota accumula il sabato\u00a0 e che si potrebbe riverberare sulla gara della domenica.<\/p>\n<p class=\"ai-optimize-64\">L\u2019aspetto pi\u00f9 critico \u00e8 in particolare la <strong>partenza<\/strong> di una gara. La partenza, infatti, \u00e8 il momento in cui si rischia di pi\u00f9 di incorrere in un incidente e quindi di cadere, \u00e8 il momento pi\u00f9 stressate e complicato della gara. Doverlo vivere due volte \u00e8 certamene una complicazione per i piloti. E anche per i team, che in caso di incidente devono gestire la riparazione delle moto ed affrontare i relativi costi\u00a0 per essere pronti a gareggiare\u00a0 il giorno dopo. Spesso non ci si pensa ma quando le moto subiscono dei danni, c\u2019\u00e8 una serie di spese che impattano nel budget di ogni team per riparare i mezzi.<\/p>\n<p class=\"ai-optimize-65\">Uno stress quindi fisico, mentale, tecnico e organizzativo che pesa sui team e sui piloti per tutte le gare dell\u2019intero calendario MotoGP 2023. La loro preoccupazione \u00e8 certamente lecita. Il fatto che la Formula 1 corra la sprint race solo per 6 gare su 24 fa capire che ci sono dei motivi, non solo organizzativi, che portano ad una scelta di questo tipo.<\/p>\n<h3 class=\"ai-optimize-66\">Aspetti positivi della sprint race<\/h3>\n<p class=\"ai-optimize-67\">Noi guardiamo alla sprint race con gli occhi dell\u2019agenzia di marketing e anche con gli occhi dei tifosi e quindi per noi \u00e8 senza dubbio un\u2019aggiunta interessante che va ad aumentare la qualit\u00e0 della <strong>property.<\/strong> Avere un programma in pista cos\u00ec ricco nella giornata di sabato \u00e8 certamente un plus per il pubblico, soprattutto per quello che si reca in circuito e che magari ha sempre considerato il sabato meno interessante della domenica.<\/p>\n<p class=\"ai-optimize-68\">La possibilit\u00e0, inoltre, di avere una finestra dedicata all\u2019 interazione con i fans \u00e8 un altro aspetto importante che nella MotoGP mancava. Si parla sempre di engagement e di migliorare la fan experience; questo significa anche offrire ai fans qualcosa che \u00e8 legato direttamente ai piloti e ai team, cos\u00ec come accade in Formula 1.<\/p>\n<p class=\"ai-optimize-69\">\u00c8 stressate per i piloti? Certo che s\u00ec, loro sono l\u00ec per correre a oltre 300 km\/h pi\u00f9 che per firmare autografi, ma lo possono fare perch\u00e9 il pubblico li guarda e li segue, paga i biglietti, i trasferimenti, acquista il loro merchandising ecc. qualcosa in cambio lo si deve dare, la sola performance in pista non basta pi\u00f9.<\/p>\n<p class=\"ai-optimize-70\">Secondo aspetto interessate, soprattutto dal punto di vista del marketing e della comunicazione, \u00e8 che avere una gara in pi\u00f9 con un podio a s\u00e9 stante offre la possibilit\u00e0 ad eventuali sponsor di avere un ulteriore strumento su cui investire e quindi da comunicare. Le offerte in termini di sponsorship aumentano, e questo a noi fa piacere.<\/p>\n<p class=\"ai-optimize-71\">Come tutti i cambiamenti del Calendario MotoGP 2023, anche questo avr\u00e0 necessit\u00e0 di un po&#8217; di tempo per essere digerito, ma ci auguriamo che migliorer\u00e0 il format. Non ci resta che aspettare qualche mese.2023 MotoGP CALENDAR PDF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mancano poche gare alla fine del Campionato MotoGP 2022 e c\u2019\u00e8 gi\u00e0 molta curiosit\u00e0 e attesa per il calendario 2023. Dopo l\u2019uscita del calendario 2023 della Formula 1, sono sorte infatti molte domande e dubbi su quello che sar\u00e0 il tour delle due ruote. I due campionati, infatti, a volte corrono negli stessi circuiti e [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":193208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-238632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motogp"],"acf":[],"contentshake_article_id":"","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MotoGP Calendar 2023. New races and downloadable PDF.<\/title>\n<meta name=\"description\" content=\"The 2023 MotoGP calendar proposes 21 races, starting in Portugal in March and ending in Valencia in late November.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The 2023 MotoGP Calendar. With new competitions and downloadable PDF.\" \/>\n<meta property=\"og:description\" content=\"The 2023 MotoGP calendar proposes 21 races, starting in Portugal in March and ending in Valencia in late November.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/\" \/>\n<meta property=\"og:site_name\" content=\"RTR Sports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RTRSportsMarketing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvia Schweiger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rtrsports\" \/>\n<meta name=\"twitter:site\" content=\"@rtrsports\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Schweiger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/\"},\"author\":{\"name\":\"Silvia Schweiger\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#\\\/schema\\\/person\\\/7bb165381d5e3404094e095cabc0167e\"},\"headline\":\"The 2023 MotoGP Calendar. With new competitions and downloadable PDF.\",\"datePublished\":\"2022-09-30T13:39:49+00:00\",\"dateModified\":\"2025-07-01T13:30:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/\"},\"wordCount\":2318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rtrsports.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/motogp-4.jpg\",\"articleSection\":[\"MotoGP\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/\",\"url\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/\",\"name\":\"MotoGP Calendar 2023. New races and downloadable PDF.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rtrsports.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/motogp-4.jpg\",\"datePublished\":\"2022-09-30T13:39:49+00:00\",\"dateModified\":\"2025-07-01T13:30:34+00:00\",\"description\":\"The 2023 MotoGP calendar proposes 21 races, starting in Portugal in March and ending in Valencia in late November.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rtrsports.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/motogp-4.jpg\",\"contentUrl\":\"https:\\\/\\\/rtrsports.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/motogp-4.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"2023 MotoGP Calendar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/blog\\\/the-calendar-motogp-2023-new-race-and-sprint-race\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The 2023 MotoGP Calendar. With new competitions and downloadable PDF.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/\",\"name\":\"RTR Sports Marketing\",\"description\":\"RTR Sports Marketing is a global motorsport sponsorship agency and consultancy, specialized in Formula 1 and MotoGP, and active across all major international racing series including Formula E, NASCAR, WEC, WRC and Dakar, helping brands build data-driven, high-performance sponsorship programs.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#organization\"},\"alternateName\":\"RTR Sports\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#organization\",\"name\":\"RTR Sports Marketing\",\"alternateName\":\"RTR sports\",\"url\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rtrsports.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/rtrsports-anniversary-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rtrsports.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/rtrsports-anniversary-1.jpg\",\"width\":946,\"height\":260,\"caption\":\"RTR Sports Marketing\"},\"image\":{\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RTRSportsMarketing\\\/\",\"https:\\\/\\\/x.com\\\/rtrsports\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rtr-sports-marketing\\\/\"],\"description\":\"RTR Sports Marketing is a global motorsport sponsorship agency and consultancy, specialized in Formula 1 and MotoGP, and active across all major international racing series including Formula E, NASCAR, WEC, WRC and Dakar, helping brands build data-driven, high-performance sponsorship programs.\",\"email\":\"info@rtrsports.com\",\"legalName\":\"RTR Sports Marketing LTD\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/#\\\/schema\\\/person\\\/7bb165381d5e3404094e095cabc0167e\",\"name\":\"Silvia Schweiger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69d98ba8290517744bdcb27b64c18a4a735ed0cac4d0bd39ea418fe3b1019aef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69d98ba8290517744bdcb27b64c18a4a735ed0cac4d0bd39ea418fe3b1019aef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69d98ba8290517744bdcb27b64c18a4a735ed0cac4d0bd39ea418fe3b1019aef?s=96&d=mm&r=g\",\"caption\":\"Silvia Schweiger\"},\"description\":\"Associate Director, Executive Marketing and Commercial at RTR Sports Marketing, a London-based sports marketing company specializing in motorsport for over 25 years. Without sports, life is boring\",\"sameAs\":[\"https:\\\/\\\/stg-rtrsportscom-rtrstaging.kinsta.cloud\"],\"url\":\"https:\\\/\\\/rtrsports.com\\\/en\\\/author\\\/silvia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MotoGP Calendar 2023. New races and downloadable PDF.","description":"The 2023 MotoGP calendar proposes 21 races, starting in Portugal in March and ending in Valencia in late November.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/","og_locale":"en_US","og_type":"article","og_title":"The 2023 MotoGP Calendar. With new competitions and downloadable PDF.","og_description":"The 2023 MotoGP calendar proposes 21 races, starting in Portugal in March and ending in Valencia in late November.","og_url":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/","og_site_name":"RTR Sports","article_publisher":"https:\/\/www.facebook.com\/RTRSportsMarketing\/","og_image":[{"width":2000,"height":1333,"url":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-4.jpg","type":"image\/jpeg"}],"author":"Silvia Schweiger","twitter_card":"summary_large_image","twitter_creator":"@rtrsports","twitter_site":"@rtrsports","twitter_misc":{"Written by":"Silvia Schweiger","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#article","isPartOf":{"@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/"},"author":{"name":"Silvia Schweiger","@id":"https:\/\/rtrsports.com\/en\/#\/schema\/person\/7bb165381d5e3404094e095cabc0167e"},"headline":"The 2023 MotoGP Calendar. With new competitions and downloadable PDF.","datePublished":"2022-09-30T13:39:49+00:00","dateModified":"2025-07-01T13:30:34+00:00","mainEntityOfPage":{"@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/"},"wordCount":2318,"commentCount":0,"publisher":{"@id":"https:\/\/rtrsports.com\/en\/#organization"},"image":{"@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#primaryimage"},"thumbnailUrl":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-4.jpg","articleSection":["MotoGP"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/","url":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/","name":"MotoGP Calendar 2023. New races and downloadable PDF.","isPartOf":{"@id":"https:\/\/rtrsports.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#primaryimage"},"image":{"@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#primaryimage"},"thumbnailUrl":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-4.jpg","datePublished":"2022-09-30T13:39:49+00:00","dateModified":"2025-07-01T13:30:34+00:00","description":"The 2023 MotoGP calendar proposes 21 races, starting in Portugal in March and ending in Valencia in late November.","breadcrumb":{"@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#primaryimage","url":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-4.jpg","contentUrl":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/07\/motogp-4.jpg","width":2000,"height":1333,"caption":"2023 MotoGP Calendar"},{"@type":"BreadcrumbList","@id":"https:\/\/rtrsports.com\/en\/blog\/the-calendar-motogp-2023-new-race-and-sprint-race\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rtrsports.com\/en\/"},{"@type":"ListItem","position":2,"name":"The 2023 MotoGP Calendar. With new competitions and downloadable PDF."}]},{"@type":"WebSite","@id":"https:\/\/rtrsports.com\/en\/#website","url":"https:\/\/rtrsports.com\/en\/","name":"RTR Sports Marketing","description":"RTR Sports Marketing is a global motorsport sponsorship agency and consultancy, specialized in Formula 1 and MotoGP, and active across all major international racing series including Formula E, NASCAR, WEC, WRC and Dakar, helping brands build data-driven, high-performance sponsorship programs.","publisher":{"@id":"https:\/\/rtrsports.com\/en\/#organization"},"alternateName":"RTR Sports","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rtrsports.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/rtrsports.com\/en\/#organization","name":"RTR Sports Marketing","alternateName":"RTR sports","url":"https:\/\/rtrsports.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/rtrsports.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/01\/rtrsports-anniversary-1.jpg","contentUrl":"https:\/\/rtrsports.com\/wp-content\/uploads\/2024\/01\/rtrsports-anniversary-1.jpg","width":946,"height":260,"caption":"RTR Sports Marketing"},"image":{"@id":"https:\/\/rtrsports.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RTRSportsMarketing\/","https:\/\/x.com\/rtrsports","https:\/\/www.linkedin.com\/company\/rtr-sports-marketing\/"],"description":"RTR Sports Marketing is a global motorsport sponsorship agency and consultancy, specialized in Formula 1 and MotoGP, and active across all major international racing series including Formula E, NASCAR, WEC, WRC and Dakar, helping brands build data-driven, high-performance sponsorship programs.","email":"info@rtrsports.com","legalName":"RTR Sports Marketing LTD","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/rtrsports.com\/en\/#\/schema\/person\/7bb165381d5e3404094e095cabc0167e","name":"Silvia Schweiger","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/69d98ba8290517744bdcb27b64c18a4a735ed0cac4d0bd39ea418fe3b1019aef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69d98ba8290517744bdcb27b64c18a4a735ed0cac4d0bd39ea418fe3b1019aef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69d98ba8290517744bdcb27b64c18a4a735ed0cac4d0bd39ea418fe3b1019aef?s=96&d=mm&r=g","caption":"Silvia Schweiger"},"description":"Associate Director, Executive Marketing and Commercial at RTR Sports Marketing, a London-based sports marketing company specializing in motorsport for over 25 years. Without sports, life is boring","sameAs":["https:\/\/stg-rtrsportscom-rtrstaging.kinsta.cloud"],"url":"https:\/\/rtrsports.com\/en\/author\/silvia\/"}]}},"_links":{"self":[{"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/posts\/238632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/comments?post=238632"}],"version-history":[{"count":4,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/posts\/238632\/revisions"}],"predecessor-version":[{"id":293281,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/posts\/238632\/revisions\/293281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/media\/193208"}],"wp:attachment":[{"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/media?parent=238632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/categories?post=238632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rtrsports.com\/en\/wp-json\/wp\/v2\/tags?post=238632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}